{"id":10614,"date":"2013-06-10T04:06:13","date_gmt":"2013-06-10T02:06:13","guid":{"rendered":"http:\/\/www.michael-schumacher.es\/noticias-f1\/?p=10614"},"modified":"2013-06-10T04:06:13","modified_gmt":"2013-06-10T02:06:13","slug":"balance-gp-de-canada-montreal-2013-force-india","status":"publish","type":"post","link":"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/06\/10\/balance-gp-de-canada-montreal-2013-force-india\/","title":{"rendered":"Balance GP de Canad\u00e1, Montreal 2013. Force India"},"content":{"rendered":"<p><a href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2012\/08\/david_sarro.di-resta-1.jpg\"><img loading=\"lazy\" class=\"alignleft\" alt=\"Paul di Resta 1 \" src=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2012\/08\/david_sarro.di-resta-1.jpg\" width=\"201\" height=\"133\" \/><\/a>El equipo Force India que celebraba su carrera 100 hoy, logr\u00f3 finalizar\u00a0 sumando siete puntos, con sus dos pilotos acabando entre los diez primeros y reforzando su quinta posici\u00f3n en el Mundial de Constructores, por lo que el equipo abandona Montreal contentos con el resultado y esperando que sean igual de competitivos en el pr\u00f3ximo GP, su carrera de casa en Silverstone.<\/p>\n<p><!--more--> <!--noteaser--><\/p>\n<p><a href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2012\/08\/david_sarro.di-resta-1.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-3231\" alt=\"Paul di Resta 1 \" src=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2012\/08\/david_sarro.di-resta-1.jpg\" width=\"600\" height=\"399\" srcset=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2012\/08\/david_sarro.di-resta-1.jpg 600w, http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2012\/08\/david_sarro.di-resta-1-300x199.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>El equipo Force India que celebraba su carrera 100 hoy, logr\u00f3 finalizar\u00a0 sumando siete puntos, con sus dos pilotos acabando entre los diez primeros y reforzando su quinta posici\u00f3n en el Mundial de Constructores, por lo que el equipo abandona Montreal contentos con el resultado y esperando que sean igual de competitivos en el pr\u00f3ximo GP, su carrera de casa en Silverstone.<\/p>\n<p>&nbsp;<\/p>\n<p>Paul Di Resta ha tenido una muy buena carrera ya que sal\u00eda en posici\u00f3n 17\u00ba y ha finalizado s\u00e9ptimo en una estrategia de una parada. Adrian Sutil ha finalizado en posici\u00f3n d\u00e9cima, pero en una carrera muy accidentada para \u00e9l, donde hizo un trompo, le toc\u00f3 con Maldonado y fue penalizado con un drive-through, aun as\u00ed logr\u00f3 sumar un punto, por lo que es sin duda, un buen resultado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Paul Di Resta:<\/strong> <em>\u00abPara terminar la carrera en el s\u00e9ptimo despu\u00e9s de haber iniciado 17 es un gran resultado y un gran trabajo del equipo. Yo no pude conseguir los datos de tandas largas el viernes por lo que se siente m\u00e1s dulce hacer esta estrategia de una \u00fanica parada con una larga tanda con los medios. Tambi\u00e9n se siente bien volver tan fuerte despu\u00e9s de una sesi\u00f3n de calificaci\u00f3n dif\u00edcil. Los neum\u00e1ticos duraron muy bien, los tiempos de vuelta eran competitivos y el equipo me dijo que era mi decisi\u00f3n acerca de cu\u00e1ndo hacer mi parada. Tan pronto como me sent\u00ed los neum\u00e1ticos empezaron a deshacerse entr\u00e9, entonces era el caso de cuidar de los superblandos para las \u00faltimas vueltas\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Adrian Sutil:<\/strong> <em>\u00abEsa carrera fue toda una aventura, as\u00ed que es bueno conseguir un punto dado todo lo que pas\u00f3. Tuve un trompo cuando intentaba adelantar a Bottas, lo que me cost\u00f3 un buen n\u00famero de posiciones y yo tuve la suerte de que nadie me chocara cuando estaba en el medio de la pista. Volv\u00ed a la pista y\u00a0 el grupo\u00a0 estaba muy junto, es cuando Maldonado vino detr\u00e1s de m\u00ed y da\u00f1\u00f3 el aler\u00f3n trasero. A pesar de todas esas cosas que me estaba quedando octavo hasta la penalizaci\u00f3n del drive-through. No creo que fuera una pena justa porque yo tambi\u00e9n ten\u00eda que muchos coches por vuelta, que a veces me costaba una o dos vueltas pasarles y eso es normal para este circuito. La pena me cost\u00f3 dos posiciones y tres puntos\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Robert Fernley, el jefe del equipo:<\/strong> <em>\u00abEs genial ver a nuestros dos coches en los puntos en nuestro Gran Premio n\u00famero 100. Asciende\u00a0 nuestra cuenta personal a 51 puntos y fortalece nuestra quinta posici\u00f3n en el campeonato. Paul mostr\u00f3 su esp\u00edritu de lucha con una remarcable conducci\u00f3n el s\u00e9ptimo con una sola parada. El coche ten\u00eda un buen ritmo y se ve\u00eda despu\u00e9s que sus neum\u00e1ticos de compuesto medio estaban extremadamente bien. Yo no creo que nadie pensaba que hab\u00eda 56 vueltas estos neum\u00e1ticos, pero \u00e9l los uso. La tarde de Adrian era bastante m\u00e1s agitada, pero fue una decepci\u00f3n para recoger la pena en las \u00faltimas vueltas, as\u00ed que es algo que tenemos que revisar. En general, creo que deber\u00edamos estar contentos con el resultado despu\u00e9s de un fin de semana dif\u00edcil. El coche sigue siendo competitivo y se espera que puedan llevarlo como base a nuestra carrera de casa en Silverstone a finales del mes\u00bb.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Imagen:<\/strong> David Sarr\u00f3<\/p>\n<div class=\"sharedaddy sd-sharing-enabled\"><div class=\"robots-nocontent sd-block sd-social sd-social-official sd-sharing\"><h3 class=\"sd-title\">Opciones Sociales:<\/h3><div class=\"sd-content\"><ul><li class=\"share-facebook\"><div class=\"fb-share-button\" data-href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/06\/10\/balance-gp-de-canada-montreal-2013-force-india\/\" data-layout=\"button_count\"><\/div><\/li><li class=\"share-twitter\"><a href=\"https:\/\/twitter.com\/share\" class=\"twitter-share-button\" data-url=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/06\/10\/balance-gp-de-canada-montreal-2013-force-india\/\" data-text=\"Balance GP de Canad\u00e1, Montreal 2013. Force India\"  >Tweet<\/a><\/li><li class=\"share-email\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-email sd-button\" href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/06\/10\/balance-gp-de-canada-montreal-2013-force-india\/?share=email\" target=\"_blank\" title=\"Haz clic para enviar por correo electr\u00f3nico a un amigo\"><span>Correo electr\u00f3nico<\/span><\/a><\/li><li class=\"share-end\"><\/li><\/ul><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El equipo Force India que celebraba su carrera 100 hoy, logr\u00f3 finalizar\u00a0 sumando siete puntos, con sus dos pilotos acabando entre los diez primeros y reforzando su quinta posici\u00f3n en el Mundial de Constructores, por lo que el equipo abandona Montreal contentos con el resultado y esperando que sean igual de competitivos en el pr\u00f3ximo [&hellip;]<\/p>\n<div class=\"sharedaddy sd-sharing-enabled\"><div class=\"robots-nocontent sd-block sd-social sd-social-official sd-sharing\"><h3 class=\"sd-title\">Opciones Sociales:<\/h3><div class=\"sd-content\"><ul><li class=\"share-facebook\"><div class=\"fb-share-button\" data-href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/06\/10\/balance-gp-de-canada-montreal-2013-force-india\/\" data-layout=\"button_count\"><\/div><\/li><li class=\"share-twitter\"><a href=\"https:\/\/twitter.com\/share\" class=\"twitter-share-button\" data-url=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/06\/10\/balance-gp-de-canada-montreal-2013-force-india\/\" data-text=\"Balance GP de Canad\u00e1, Montreal 2013. Force India\"  >Tweet<\/a><\/li><li class=\"share-email\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-email sd-button\" href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/06\/10\/balance-gp-de-canada-montreal-2013-force-india\/?share=email\" target=\"_blank\" title=\"Haz clic para enviar por correo electr\u00f3nico a un amigo\"><span>Correo electr\u00f3nico<\/span><\/a><\/li><li class=\"share-end\"><\/li><\/ul><\/div><\/div><\/div>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[4,3],"tags":[373,732,401,64,417,110,17,126,15,6,8,451,109,733,113],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p27q3P-2Lc","_links":{"self":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/posts\/10614"}],"collection":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/comments?post=10614"}],"version-history":[{"count":0,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/posts\/10614\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/media?parent=10614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/categories?post=10614"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/tags?post=10614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}