{"id":13128,"date":"2013-10-13T23:51:59","date_gmt":"2013-10-13T21:51:59","guid":{"rendered":"http:\/\/www.michael-schumacher.es\/noticias-f1\/?p=13128"},"modified":"2013-10-13T22:03:22","modified_gmt":"2013-10-13T20:03:22","slug":"balance-gp-de-japon-suzuka-2013-force-india","status":"publish","type":"post","link":"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/10\/13\/balance-gp-de-japon-suzuka-2013-force-india\/","title":{"rendered":"Balance GP de Jap\u00f3n, Suzuka 2013. Force India"},"content":{"rendered":"<p><a href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/adrian_sutil_test-bcn-2013_david-sarro.jpg\"><img loading=\"lazy\" class=\"alignleft\" alt=\"Adrian Sutil - Test Bcn 2013 - David Sarr\u00f3\" src=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/adrian_sutil_test-bcn-2013_david-sarro.jpg\" width=\"200\" height=\"133\" \/><\/a>El equipo Force India se va de Suzuka sin conseguir sumar ning\u00fan punto, aunque no es una sorpresa, ya que el equipo ya esperaba tener una dif\u00edcil carrera en este circuito. Aunque se han quedado cerca de la zona de puntos les falt\u00f3 ritmo y un mejor rendimiento con los neum\u00e1ticos. Aunque una vez dejado atr\u00e1s Jap\u00f3n son optimistas sobre las restantes carreras y sobre la India la carrera de casa del equipo.<\/p>\n<p><!--more--> <!--noteaser--><\/p>\n<p><a href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/adrian_sutil_test-bcn-2013_david-sarro.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8278\" alt=\"Adrian Sutil - Test Bcn 2013 - David Sarr\u00f3\" src=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/adrian_sutil_test-bcn-2013_david-sarro.jpg\" width=\"650\" height=\"433\" srcset=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/adrian_sutil_test-bcn-2013_david-sarro.jpg 650w, http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/adrian_sutil_test-bcn-2013_david-sarro-300x199.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El equipo Force India se va de Suzuka sin conseguir sumar ning\u00fan punto, aunque no es una sorpresa, ya que el equipo ya esperaba tener una dif\u00edcil carrera en este circuito. Aunque se han quedado cerca de la zona de puntos les falt\u00f3 ritmo y un mejor rendimiento con los neum\u00e1ticos. Aunque una vez dejado atr\u00e1s Jap\u00f3n son optimistas sobre las restantes carreras y sobre la India la carrera de casa del equipo.<\/p>\n<p>&nbsp;<\/p>\n<p>Paul Di Resta que no tuvo una buena salida, ya que perdi\u00f3 pronto posiciones y su lucha con Button ayud\u00f3 a desgastar m\u00e1s sus gomas por lo que le duraron cinco vueltas menos de lo que ten\u00edan planeado, finalmente\u00a0 termin\u00f3 en posici\u00f3n 11\u00ba, pero quiere sacar lo positivo del fin de semana e ir a la India a por puntos. Adrian Sutil ha finalizado en la posici\u00f3n 14\u00ba. en un fin de semana muy duro, saliendo desde atr\u00e1s, adem\u00e1s de tener sobreviraje en el coche y no tener el ritmo de carrera.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Paul Di Resta:<\/strong> <em>\u201cAl principio de la carrera no he tenido una buena salida y algunos coches han venido a por m\u00ed pas\u00e1ndome, y luego perd\u00ed en la primera parada en boxes porque el Williams de Bottas nos adelant\u00f3. Eso comprometi\u00f3 nuestro segundo stint, por lo que fuimos muy agresivos con una segunda parada temprano para conseguir la posici\u00f3n en pista y pasar por delante del Williams. El coche iba mejor en el tramo final y parec\u00eda que est\u00e1bamos en camino de un punto. Al final nos quedamos unas cinco vueltas demasiado cortas con la vida de los neum\u00e1ticos, no pod\u00eda defenderme de Jenson [Button]. Con cuatro carreras por delante tenemos que sacar lo positivo de este fin de semana y viajar a la India decididos a volver a los puntos\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Adrian Sutil:<\/strong> <em>\u201cHa sido un fin de semana muy duro, y partir de la parte posterior de la parrilla hace que sea dif\u00edcil acercarse a los puntos. Al final he terminado P14 y ten\u00eda algunas buenas batallas, pero hab\u00eda un mont\u00f3n de sobreviraje en el coche y no era f\u00e1cil ser consistente. La mejor parte de la carrera fue el comienzo porque me adelante a P16, pero simplemente no ten\u00eda el ritmo de carrera que necesitamos hoy y no pod\u00eda obtener el rendimiento de los neum\u00e1ticos.\u201d<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Robert Fernley, director del equipo:<\/strong> <em>\u201cNosotros no ocultamos el hecho de que Suzuka iba a ser el circuito m\u00e1s dif\u00edcil para nosotros en la segunda parte de la temporada. As\u00ed que no fue una sorpresa que los puntos fueran dif\u00edciles de conseguir hoy. Paul estuvo en el P11, pero su estrategia de carrera se vio obstaculizada en el segundo stint cuando corr\u00eda detr\u00e1s Bottas. Finalmente se libr\u00f3 del Williams parando temprano en su segunda parada, pero nos faltaba el ritmo para defenderse de la recuperaci\u00f3n de Button y nos cost\u00f3 el punto final. Con Adrian fue una historia similar mientras corr\u00eda detr\u00e1s de Maldonado durante gran parte de la carrera y tuvo problemas con el rendimiento del neum\u00e1tico. As\u00ed que ha sido una lucha cuesta arriba para nosotros, pero seguimos siendo optimistas mientras nos dirigimos a la India para la carrera de casa del equipo. Las pr\u00f3ximas pistas deber\u00edan jugar m\u00e1s a nuestro favor y darnos la oportunidad de volver a sumar puntos regulares\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Imagen:<\/strong> David Sarr\u00f3<\/p>\n<div class=\"sharedaddy sd-sharing-enabled\"><div class=\"robots-nocontent sd-block sd-social sd-social-official sd-sharing\"><h3 class=\"sd-title\">Opciones Sociales:<\/h3><div class=\"sd-content\"><ul><li class=\"share-facebook\"><div class=\"fb-share-button\" data-href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/10\/13\/balance-gp-de-japon-suzuka-2013-force-india\/\" data-layout=\"button_count\"><\/div><\/li><li class=\"share-twitter\"><a href=\"https:\/\/twitter.com\/share\" class=\"twitter-share-button\" data-url=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/10\/13\/balance-gp-de-japon-suzuka-2013-force-india\/\" data-text=\"Balance GP de Jap\u00f3n, Suzuka 2013. Force India\"  >Tweet<\/a><\/li><li class=\"share-email\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-email sd-button\" href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/10\/13\/balance-gp-de-japon-suzuka-2013-force-india\/?share=email\" target=\"_blank\" title=\"Haz clic para enviar por correo electr\u00f3nico a un amigo\"><span>Correo electr\u00f3nico<\/span><\/a><\/li><li class=\"share-end\"><\/li><\/ul><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El equipo Force India se va de Suzuka sin conseguir sumar ning\u00fan punto, aunque no es una sorpresa, ya que el equipo ya esperaba tener una dif\u00edcil carrera en este circuito. Aunque se han quedado cerca de la zona de puntos les falt\u00f3 ritmo y un mejor rendimiento con los neum\u00e1ticos. Aunque una vez dejado [&hellip;]<\/p>\n<div class=\"sharedaddy sd-sharing-enabled\"><div class=\"robots-nocontent sd-block sd-social sd-social-official sd-sharing\"><h3 class=\"sd-title\">Opciones Sociales:<\/h3><div class=\"sd-content\"><ul><li class=\"share-facebook\"><div class=\"fb-share-button\" data-href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/10\/13\/balance-gp-de-japon-suzuka-2013-force-india\/\" data-layout=\"button_count\"><\/div><\/li><li class=\"share-twitter\"><a href=\"https:\/\/twitter.com\/share\" class=\"twitter-share-button\" data-url=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/10\/13\/balance-gp-de-japon-suzuka-2013-force-india\/\" data-text=\"Balance GP de Jap\u00f3n, Suzuka 2013. Force India\"  >Tweet<\/a><\/li><li class=\"share-email\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-email sd-button\" href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/10\/13\/balance-gp-de-japon-suzuka-2013-force-india\/?share=email\" target=\"_blank\" title=\"Haz clic para enviar por correo electr\u00f3nico a un amigo\"><span>Correo electr\u00f3nico<\/span><\/a><\/li><li class=\"share-end\"><\/li><\/ul><\/div><\/div><\/div>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[4,3],"tags":[373,732,401,64,110,17,126,15,6,8,1220,109,733,1465,113],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p27q3P-3pK","_links":{"self":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/posts\/13128"}],"collection":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/comments?post=13128"}],"version-history":[{"count":0,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/posts\/13128\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/media?parent=13128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/categories?post=13128"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/tags?post=13128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}