{"id":13829,"date":"2013-11-16T14:24:41","date_gmt":"2013-11-16T13:24:41","guid":{"rendered":"http:\/\/www.michael-schumacher.es\/noticias-f1\/?p=13829"},"modified":"2013-11-16T06:46:01","modified_gmt":"2013-11-16T05:46:01","slug":"entrenamientos-gp-de-ee-uu-austin-2013-lotus","status":"publish","type":"post","link":"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/11\/16\/entrenamientos-gp-de-ee-uu-austin-2013-lotus\/","title":{"rendered":"Entrenamientos GP de EE.UU, Austin 2013. Lotus"},"content":{"rendered":"<p><a href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/romain-grosjean-test-2-bcn-2013-dia-2.jpg\"><img loading=\"lazy\" class=\"alignleft\" alt=\"romain-grosjean-test-2--bcn-2013-dia-2\" src=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/romain-grosjean-test-2-bcn-2013-dia-2.jpg\" width=\"200\" height=\"123\" \/><\/a>El equipo Lotus ha tenido una buena sesi\u00f3n de entrenamientos, incluso sorprendentemente el sustituto de Raikkonen, Kovalainen ha tenido una r\u00e1pida adaptaci\u00f3n al monoplaza y ha terminado entre los cinco primeros, lo que sin duda es un buen s\u00edntoma para el equipo y sus aspiraciones. Seguir\u00e1n trabajando para mejorar de cara a la calificaci\u00f3n y la carrera y lograr un buen resultado.<\/p>\n<p><!--more--> <!--noteaser--><\/p>\n<p><a href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/romain-grosjean-test-2-bcn-2013-dia-2.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-8117\" alt=\"romain-grosjean-test-2--bcn-2013-dia-2\" src=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/romain-grosjean-test-2-bcn-2013-dia-2.jpg\" width=\"650\" height=\"400\" srcset=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/romain-grosjean-test-2-bcn-2013-dia-2.jpg 650w, http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-content\/uploads\/2013\/03\/romain-grosjean-test-2-bcn-2013-dia-2-300x184.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El equipo Lotus ha tenido una buena sesi\u00f3n de entrenamientos, incluso sorprendentemente el sustituto de Raikkonen, Kovalainen ha tenido una r\u00e1pida adaptaci\u00f3n al monoplaza y ha terminado entre los cinco primeros, lo que sin duda es un buen s\u00edntoma para el equipo y sus aspiraciones. Seguir\u00e1n trabajando para mejorar de cara a la calificaci\u00f3n y la carrera y lograr un buen resultado.<\/p>\n<p>&nbsp;<\/p>\n<p>Romain Grosjean no ha tenido un d\u00eda perfecto y les cost\u00f3 conseguir la puesta a punto adecuada, pero al final del d\u00eda, el ritmo en tandas largas hab\u00eda mejorado\u00a0 y termin\u00f3 m\u00e1s contento. Aunque si est\u00e1 satisfecho con su nuevo compa\u00f1ero para las dos \u00faltimas carreras, ya que se ha puesto al d\u00eda deprisa, lo que es bueno para los objetivos del equipo y de Romain,\u00a0 que intentar\u00e1 hacer pasar un mal rato a Ferrari y Mercedes. La primera sesi\u00f3n consigui\u00f3 finalizar en posici\u00f3n 11\u00ba y la segunda en posici\u00f3n 8\u00ba pero seguir\u00e1n trabajando para mejorar y lograr una buena calificaci\u00f3n. Heikki Kovalainen no sab\u00eda qu\u00e9 esperar, con tan poco tiempo para ponerse al d\u00eda, sin embargo ha tenido buenas sesiones y con buen ritmo,\u00a0 adem\u00e1s ha seguido el programa y ha tenido un buen equilibrio, sinti\u00e9ndose inmediatamente c\u00f3modo en el coche. As\u00ed que ha finalizado la primera sesi\u00f3n en posici\u00f3n 13\u00ba y la segunda en posici\u00f3n 5\u00ba. Espera seguir mejorado y poder estar en el top ten.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Romain Grosjean:<\/strong> <em>\u201cNo es el d\u00eda perfecto para ser honesto, ya que tom\u00f3 un poco de tiempo conseguir la puesta a punto adecuada, pero al final del d\u00eda, el ritmo en tandas largas era bastante bueno y yo estaba mucho m\u00e1s contento con el coche. No es un circuito f\u00e1cil y la superficie ha cambiado un poco desde el a\u00f1o pasado con un nivel de agarre diferente, as\u00ed que tenemos mucho trabajo que hacer. Estamos aqu\u00ed para tratar de hacer pasar un mal rato a Ferrari y Mercedes y Heikki tuvo un buen d\u00eda al ponerse al d\u00eda muy r\u00e1pidamente. Obviamente, \u00e9l sabe de F\u00f3rmula 1 y sabe los neum\u00e1ticos, as\u00ed que no hab\u00eda raz\u00f3n por la que no tendr\u00eda la velocidad. Es bueno tenerlo en el ritmo ya que tenemos m\u00e1s datos para trabajar. Esto nos da m\u00e1s conocimiento y por lo tanto, estamos en una mejor posici\u00f3n para conseguir el m\u00e1ximo de puntos que podamos. Hoy la simulaci\u00f3n de la clasificaci\u00f3n no era perfecta, pero hemos mejorado a partir de ese plazo y vamos a seguir trabajando ma\u00f1ana por la ma\u00f1ana para aprender como la pista est\u00e1 evolucionando. Esperemos que vayamos a tener una buena puesta a punto y algunas carreras limpias agradables a trav\u00e9s de las sesiones\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Heikki Kovalainen:<\/strong> <em>\u201cYo no sab\u00eda qu\u00e9 esperar, para ser honesto, ya que hab\u00eda un corto espacio de preparaci\u00f3n para venir aqu\u00ed y he estado muy ocupado desde el martes por la noche. En general hemos tenido un buen d\u00eda sin problemas y el coche ha tenido un razonablemente buen equilibrio, por lo que hemos sido capaces de empezar a trabajar en el programa normal, como lo hace toda la temporada en lugar de algo en particular que utilizar para el coche. Todo se ha preparado bien para m\u00ed y me sent\u00ed inmediatamente c\u00f3modo en el coche. Creo que tenemos que mejorar un poco para ma\u00f1ana para seguir siendo competitivos, pero las tandas largas las sent\u00ed bien. Durante los recorridos m\u00e1s cortos probablemente podemos hacerlo un poco mejor, pero no es tan malo. \u00bfQui\u00e9n sabe? Es mejor no especular demasiado, podr\u00eda ser un desastre o que podr\u00eda ser bueno. Nunca se sabe acerca de estas cosas. Si podemos mejorar a partir de hoy y saltar lejos en la velocidad, mientras que mantenemos el enfoque para obtener el m\u00e1ximo rendimiento del coche, entonces podr\u00edamos ir bien. Por otra parte esta tan cerca aqu\u00ed, si el ritmo se cae un poco de nuestros rivales que pod\u00edamos luchar y estar fuera del top ten. Vamos a ver qu\u00e9 pasa ma\u00f1ana\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Alan Permane, director de operaciones de pista:<\/strong> <em>\u00abObviamente, nuestro programa se ha visto interrumpido por la ma\u00f1ana, por lo que le ha restado un tiempo muy valioso a Heikki para probar el E21, pero no parece haberle afectado y se ha sentido inmediatamente muy c\u00f3modo con el coche. Romain ha tenido un par de problemas con los frenos en sus tandas de baja carga de gasolina, con lo que tendremos que mejorarlo para ma\u00f1ana. Es dif\u00edcil sacar conclusiones de la sesi\u00f3n matinal, pero por la tarde salimos contentos del rendimiento de ambos pilotos, especialmente de las tandas largas\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"sharedaddy sd-sharing-enabled\"><div class=\"robots-nocontent sd-block sd-social sd-social-official sd-sharing\"><h3 class=\"sd-title\">Opciones Sociales:<\/h3><div class=\"sd-content\"><ul><li class=\"share-facebook\"><div class=\"fb-share-button\" data-href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/11\/16\/entrenamientos-gp-de-ee-uu-austin-2013-lotus\/\" data-layout=\"button_count\"><\/div><\/li><li class=\"share-twitter\"><a href=\"https:\/\/twitter.com\/share\" class=\"twitter-share-button\" data-url=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/11\/16\/entrenamientos-gp-de-ee-uu-austin-2013-lotus\/\" data-text=\"Entrenamientos GP de EE.UU, Austin 2013. Lotus\"  >Tweet<\/a><\/li><li class=\"share-email\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-email sd-button\" href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/11\/16\/entrenamientos-gp-de-ee-uu-austin-2013-lotus\/?share=email\" target=\"_blank\" title=\"Haz clic para enviar por correo electr\u00f3nico a un amigo\"><span>Correo electr\u00f3nico<\/span><\/a><\/li><li class=\"share-end\"><\/li><\/ul><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El equipo Lotus ha tenido una buena sesi\u00f3n de entrenamientos, incluso sorprendentemente el sustituto de Raikkonen, Kovalainen ha tenido una r\u00e1pida adaptaci\u00f3n al monoplaza y ha terminado entre los cinco primeros, lo que sin duda es un buen s\u00edntoma para el equipo y sus aspiraciones. Seguir\u00e1n trabajando para mejorar de cara a la calificaci\u00f3n y [&hellip;]<\/p>\n<div class=\"sharedaddy sd-sharing-enabled\"><div class=\"robots-nocontent sd-block sd-social sd-social-official sd-sharing\"><h3 class=\"sd-title\">Opciones Sociales:<\/h3><div class=\"sd-content\"><ul><li class=\"share-facebook\"><div class=\"fb-share-button\" data-href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/11\/16\/entrenamientos-gp-de-ee-uu-austin-2013-lotus\/\" data-layout=\"button_count\"><\/div><\/li><li class=\"share-twitter\"><a href=\"https:\/\/twitter.com\/share\" class=\"twitter-share-button\" data-url=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/11\/16\/entrenamientos-gp-de-ee-uu-austin-2013-lotus\/\" data-text=\"Entrenamientos GP de EE.UU, Austin 2013. Lotus\"  >Tweet<\/a><\/li><li class=\"share-email\"><a rel=\"nofollow noopener noreferrer\" data-shared=\"\" class=\"share-email sd-button\" href=\"http:\/\/www.michael-schumacher.es\/noticias-f1\/2013\/11\/16\/entrenamientos-gp-de-ee-uu-austin-2013-lotus\/?share=email\" target=\"_blank\" title=\"Haz clic para enviar por correo electr\u00f3nico a un amigo\"><span>Correo electr\u00f3nico<\/span><\/a><\/li><li class=\"share-end\"><\/li><\/ul><\/div><\/div><\/div>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[67,3],"tags":[373,3044,703,443,1490,131,393,232,434,17,15,6,83,61,62,379,26,82],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p27q3P-3B3","_links":{"self":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/posts\/13829"}],"collection":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/comments?post=13829"}],"version-history":[{"count":0,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/posts\/13829\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/media?parent=13829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/categories?post=13829"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.michael-schumacher.es\/noticias-f1\/wp-json\/wp\/v2\/tags?post=13829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}